{"id":2541,"date":"2022-08-25T12:07:00","date_gmt":"2022-08-25T12:07:00","guid":{"rendered":"https:\/\/charangalatina.cl\/nuevaweb\/shakira-se-lleva-a-sus-hijos-a-mexico-en-medio-de-desacuerdos-por-custodia-con-gerard-pique\/"},"modified":"2022-08-25T12:07:00","modified_gmt":"2022-08-25T12:07:00","slug":"shakira-se-lleva-a-sus-hijos-a-mexico-en-medio-de-desacuerdos-por-custodia-con-gerard-pique","status":"publish","type":"post","link":"https:\/\/charangalatina.cl\/nuevaweb\/shakira-se-lleva-a-sus-hijos-a-mexico-en-medio-de-desacuerdos-por-custodia-con-gerard-pique\/","title":{"rendered":"Shakira se lleva a sus hijos a M\u00e9xico en medio de desacuerdos por custodia con Gerard Piqu\u00e9."},"content":{"rendered":"<p>Shakira\u00a0se asegura de que sus hijos y los\u00a0de Gerard Piqu\u00e9\u00a0disfruten el resto del verano lejos de los focos.\u00a0La cantante de origen colombiano fue captada llegando al hermoso Los Cabos, M\u00e9xico, el 24 de junio, con\u00a0<strong>Milan<\/strong>\u00a0, de 9 a\u00f1os, y\u00a0<strong>Sasha, de<\/strong>\u00a07. Su avistamiento se produce pocos d\u00edas despu\u00e9s de que su expareja\u00a0fuera abucheada\u00a0por FC Barcelona y Real Madrid .\u00a0aficionados en un partido de f\u00fatbol en Las Vegas.<\/p>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/charangalatina.cl\/wp-content\/uploads\/2022\/08\/image-94-1024x614.png\" alt=\"\" class=\"wp-image-6950\" \/><\/figure>\n<p>No se puede negar que la familia est\u00e1 experimentando un drama desde que anunciaron su separaci\u00f3n en junio.\u00a0Las vacaciones mexicanas del colombiano se producen en medio de informes de que ha comenzado una\u00a0batalla por la custodia\u00a0entre la pareja no casada.\u00a0Seg\u00fan los informes, Shakira tiene los ojos puestos en establecerse en Miami, donde ya tiene una mansi\u00f3n glamorosa para que ellos la llamen hogar.<\/p>\n<p>Seg\u00fan los informes, el atleta est\u00e1 en contra de la medida ya que no podr\u00eda ver a los ni\u00f1os muy a menudo.\u00a0Seg\u00fan el programa, &#8216;Chisme No Like&#8217; Shakira se mantiene persistente en sus deseos y est\u00e1 dispuesta a cubrir los costos del cuidado de los ni\u00f1os.\u00a0Seg\u00fan los informes, la ex pareja tiene programada una \u00abreuni\u00f3n de emergencia\u00bb el 4 de agosto en San Diego, California, con la esperanza de llegar a un acuerdo.<\/p>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/charangalatina.cl\/wp-content\/uploads\/2022\/08\/image-97.png\" alt=\"\" class=\"wp-image-6953\" \/><\/figure>\n<p>Es genial ver que Shakira ha estado aprovechando al m\u00e1ximo su tiempo con sus hijos, ya que no puede ser f\u00e1cil para ellos durante este tiempo confuso.&nbsp;Antes de dirigirse a Los Cabos, la mam\u00e1 se asegur\u00f3 de que disfrutaran su tiempo fuera de la escuela y pasaron unos d\u00edas golpeando las olas en Asturias, Espa\u00f1a.<\/p>\n<p>Shakira y Piqu\u00e9 eran amantes del surf, por lo que no sorprende que sus hijos disfrutaran de su tiempo en el agua.\u00a0En las fotos, parec\u00eda que los ni\u00f1os ten\u00edan la ayuda de un instructor de surf para ense\u00f1arles la t\u00e9cnica correcta.\u00a0La cantante de \u201cHip&#8217;s Don&#8217;t Lie\u201d luc\u00eda como una profesional mientras se sub\u00eda a las olas.<\/p>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/charangalatina.cl\/wp-content\/uploads\/2022\/08\/image-98-1024x683.png\" alt=\"\" class=\"wp-image-6954\" \/><\/figure>\n<h4 class=\"wp-block-heading\">Un a\u00f1o duro para Shakira<\/h4>\n<p>No han sido un par de meses f\u00e1ciles para Shakira.\u00a0Justo antes de que anunciaran la separaci\u00f3n en mayo, su padre,\u00a0<strong>William Mebarak,\u00a0<\/strong>fue trasladado de urgencia al hospital\u00a0despu\u00e9s de una ca\u00edda grave que provoc\u00f3 problemas de salud continuos.<\/p>\n<p>\u00bfEn cuanto a la divisi\u00f3n?&nbsp;Shakia y Piqu\u00e9 se han mantenido callados sobre la ruptura y los rumores de su infidelidad.&nbsp;Pero su familia ha compartido algunas ideas en el camino.&nbsp;Horas despu\u00e9s de que confirmaran su ruptura, su hermana mayor&nbsp;<strong>Lucia Mebarak<\/strong>&nbsp;se encontr\u00f3 frente a reporteros desesperados.&nbsp;Cuando se le pregunt\u00f3 frente a las c\u00e1maras c\u00f3mo estaba Shakira, Mebarak respondi\u00f3: \u201cSe est\u00e1 recuperando\u201d.<\/p>\n<p>Su madre ,\u00a0<strong>Nidia Ripoll Torrad<\/strong>\u00a0, que tambi\u00e9n ha estado lidiando con el estr\u00e9s de ver a su esposo e hija sufrir,\u00a0no ha descartado por completo a\u00a0la pareja.\u00a0Ella le dijo \u00a1HOLA!\u00a0Ser\u00eda \u201cl\u00f3gico\u201d que volvieran a estar juntos.\u00a0\u201cSi eso es lo que quieren, lo que los hace felices\u201d, dijo.<\/p>\n<p>Shakira y Piqu\u00e9 anunciaron la separaci\u00f3n el 4 de junio en un comunicado conjunto a Reuters, \u00abLamentamos confirmar que nos estamos separando\u00bb.&nbsp;\u201cPor el bienestar de nuestros ni\u00f1os, que son nuestra m\u00e1xima prioridad, les pedimos que respeten su privacidad\u201d, agregaron.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Shakira\u00a0se asegura de que sus hijos y los\u00a0de Gerard Piqu\u00e9\u00a0disfruten el resto del verano lejos de los focos.\u00a0La cantante de origen colombiano fue captada llegando al hermoso Los Cabos, M\u00e9xico, el 24 de junio, con\u00a0Milan\u00a0, de 9 a\u00f1os, y\u00a0Sasha, de\u00a07. Su avistamiento se produce pocos d\u00edas despu\u00e9s de que su expareja\u00a0fuera abucheada\u00a0por FC Barcelona y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2541","post","type-post","status-publish","format-standard","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/posts\/2541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/comments?post=2541"}],"version-history":[{"count":0,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/posts\/2541\/revisions"}],"wp:attachment":[{"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/media?parent=2541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/categories?post=2541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/tags?post=2541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}