{"id":3095,"date":"2022-04-18T12:41:03","date_gmt":"2022-04-18T12:41:03","guid":{"rendered":"https:\/\/charangalatina.cl\/nuevaweb\/polemica-el-consejero-matrimonial-de-amber-heard-y-johnny-depp-revela-que-la-actriz-inicio-peleas\/"},"modified":"2022-04-18T12:41:03","modified_gmt":"2022-04-18T12:41:03","slug":"polemica-el-consejero-matrimonial-de-amber-heard-y-johnny-depp-revela-que-la-actriz-inicio-peleas","status":"publish","type":"post","link":"https:\/\/charangalatina.cl\/nuevaweb\/polemica-el-consejero-matrimonial-de-amber-heard-y-johnny-depp-revela-que-la-actriz-inicio-peleas\/","title":{"rendered":"Pol\u00e9mica: El consejero matrimonial de Amber Heard y Johnny Depp revela que la actriz inici\u00f3 peleas"},"content":{"rendered":"<p>El consejero matrimonial de Johnny Depp\u00a0y\u00a0Amber Heard\u00a0dijo el jueves que la actriz inici\u00f3 peleas f\u00edsicas m\u00e1s de una vez, pero que la pareja incurri\u00f3 en \u00ababuso mutuo\u00bb.<\/p>\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/JL2EZFFSJ5DERJJE7TNLDBLX4U.jpg\" alt=\"Otro ataque a Amber Heard en la corte: el guardaespaldas de Johnny Depp  asegur\u00f3 que golpeaba al actor y present\u00f3 fotos - Infobae\" \/><\/figure>\n<p>La Dra. Laurel Anderson, una consejera matrimonial que trabaj\u00f3 con los ex c\u00f3nyuges durante un total de 21 sesiones a partir de octubre de 2015, brind\u00f3 un revelador testimonio en video durante el juicio por difamaci\u00f3n de $100 millones de Depp en\u00a0Virginia\u00a0.\u00a0<\/p>\n<p>\u00abS\u00e9 que ella lider\u00f3 (las peleas) en m\u00e1s de una ocasi\u00f3n y las inici\u00f3 para mantenerlo con ella porque el abandono y que \u00e9l se fuera era su peor pesadilla\u00bb, dijo el Dr. Anderson.&nbsp;<\/p>\n<p>&#8216;Miss Heard inform\u00f3 que era un motivo de orgullo para ella, si se sent\u00eda irrespetada para iniciar una pelea.&nbsp;Su padre la hab\u00eda golpeado, ella no iba a terminar.<\/p>\n<p>&#8216;Si \u00e9l se iba a ir, ella lo golpear\u00eda para mantenerlo all\u00ed.&nbsp;Ella preferir\u00eda estar en una pelea a que \u00e9l se fuera.<\/p>\n<p>Cuando se le pregunt\u00f3 si fue su evaluaci\u00f3n lo que provoc\u00f3 que Depp no \u200b\u200bfuera violento con ninguna de sus otras parejas, Anderson dijo: \u00abS\u00ed\u00bb.&nbsp;<\/p>\n<p>Ella dijo: &#8216;Hab\u00eda estado bien controlado durante casi 20, 30 a\u00f1os y ambos (Depp y Heard) fueron v\u00edctimas de abuso en sus hogares.\u00a0Pens\u00e9 que hab\u00eda estado bien controlado durante d\u00e9cadas y con la se\u00f1orita Heard se desencaden\u00f3 y se involucraron en lo que vi como abuso mutuo.\u00a0<\/p>\n<p>Las notas del Dr. Anderson muestran que Heard afirm\u00f3 que Depp le dijo: &#8216;Johnny dice que a nadie le gustas, que te estoy dando fama&#8217;.\u00a0Me estoy enamorando de ti, who*e.&#8217;\u00a0El Dr. Anderson describi\u00f3 a Depp y Heard discutiendo como &#8216;yendo y viniendo dispar\u00e1ndose el uno al otro&#8217;.\u00a0No se comunican, tienen unas habilidades terribles&#8217;<\/p>\n<p>El Dr. Anderson le dio a la pareja los nombres falsos &#8216;Ann Henry&#8217; y &#8216;Joey Davis&#8217;, aparentemente para proteger sus identidades.&nbsp;<\/p>\n<p>Para su primera reuni\u00f3n, se sent\u00f3 con la ex pareja durante tres horas y media, dijo el Dr. Anderson.<\/p>\n<p>En sus notas, dijo que una vez una de las partes \u00abse fue\u00bb, pero no ten\u00eda claro qui\u00e9n.<\/p>\n<p>Las sesiones continuaron hasta marzo de 2016 cuando una de sus amigas le pidi\u00f3 a la Dra. Anderson que hiciera una visita a domicilio, pero ella se resisti\u00f3 porque nunca lo hab\u00eda hecho.<\/p>\n<p>Ella dijo: \u00abPens\u00e9 que \u00e9l (Depp) estaba teniendo dificultades en las sesiones y creo que era algo sobre el proceso entre los dos\u00bb.<\/p>\n<p>Cuando se le pregunt\u00f3 qu\u00e9 dificultad, ella dijo: &#8216;Tener una voz.&nbsp;Miss Heard ten\u00eda un estilo martillo neum\u00e1tico de hablar.&nbsp;Estaba muy excitada.&nbsp;Ten\u00eda problemas para hablar a un ritmo similar.&nbsp;Se cort\u00f3 mucho.<\/p>\n<p>Supongo que esto es lo que era.\u00a0As\u00ed es como no ten\u00eda voz.\u00a0No pod\u00eda hablar con su forma de conversaci\u00f3n r\u00e1pida, por lo que estaba realmente abrumado.<\/p>\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/s1.reutersmedia.net\/resources\/r\/?m=02&amp;d=20200724&amp;t=2&amp;i=1526974018&amp;w=780&amp;fh=&amp;fw=&amp;ll=&amp;pl=&amp;sq=&amp;r=LYNXNPEG6N0IA\" alt=\"Factbox: Johnny Depp and Amber Heard: from romance to rancor | Reuters.com\" width=\"1017\" height=\"677\" \/><\/figure>\n<p>Cuando se le pregunt\u00f3 si Heard denunci\u00f3 violencia por parte de Depp, el Dr. Anderson dijo que s\u00ed.<\/p>\n<p>Record\u00f3 haber visto fotos de Heard con la cara magullada y moretones alrededor de los ojos, aunque ella misma nunca fue testigo del abuso.&nbsp;<\/p>\n<p>Las notas del Dr. Anderson muestran que Heard afirm\u00f3 que Depp le dijo: &#8216;Johnny dice que a nadie le gustas, que te estoy dando fama&#8217;.&nbsp;Me estoy enamorando de ti, who*e.&#8217;<\/p>\n<p>El Dr. Anderson describi\u00f3 a Depp y Heard discutiendo como &#8216;yendo y viniendo dispar\u00e1ndose el uno al otro&#8217;.\u00a0No se comunican, tienen habilidades terribles.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El consejero matrimonial de Johnny Depp\u00a0y\u00a0Amber Heard\u00a0dijo el jueves que la actriz inici\u00f3 peleas f\u00edsicas m\u00e1s de una vez, pero que la pareja incurri\u00f3 en \u00ababuso mutuo\u00bb. La Dra. Laurel Anderson, una consejera matrimonial que trabaj\u00f3 con los ex c\u00f3nyuges durante un total de 21 sesiones a partir de octubre de 2015, brind\u00f3 un revelador [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3095","post","type-post","status-publish","format-standard","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/posts\/3095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/comments?post=3095"}],"version-history":[{"count":0,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/posts\/3095\/revisions"}],"wp:attachment":[{"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/media?parent=3095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/categories?post=3095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/tags?post=3095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}