{"id":3102,"date":"2022-04-12T12:36:00","date_gmt":"2022-04-12T12:36:00","guid":{"rendered":"https:\/\/charangalatina.cl\/nuevaweb\/el-implante-de-microchip-le-permite-pagar-con-la-mano\/"},"modified":"2022-04-12T12:36:00","modified_gmt":"2022-04-12T12:36:00","slug":"el-implante-de-microchip-le-permite-pagar-con-la-mano","status":"publish","type":"post","link":"https:\/\/charangalatina.cl\/nuevaweb\/el-implante-de-microchip-le-permite-pagar-con-la-mano\/","title":{"rendered":"El implante de microchip le permite pagar con la mano"},"content":{"rendered":"<p>En lugar de llevar la billetera en el bolso o en el bolsillo trasero, una empresa de tecnolog\u00eda quiere que la lleve debajo de la piel.<\/p>\n<p>\u00a1C\u00f3mo es eso por conveniencia!\u00a0O es genial o dist\u00f3pico.<\/p>\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.batiburrillo.net\/wp-content\/uploads\/2018\/11\/Co%CC%81mo-pagar-sin-efectivo-gracias-a-un-microchip-implantado-bajo-al-piel.jpg\" alt=\"C\u00f3mo pagar sin efectivo gracias a un microchip implantado bajo la piel\" \/><\/figure>\n<p>La empresa brit\u00e1nico-polaca\u00a0Walletmor\u00a0vende microchips como opciones de pago alternativas que le permiten pagar con la mano.<\/p>\n<p>Este chip es del tama\u00f1o de un grano de arroz, cuesta alrededor de $300 y no viene dentro de una tarjeta de cr\u00e9dito.\u00a0En su lugar, debe implantarse en su cuerpo, preferiblemente en su mano.<\/p>\n<p>Una vez que lo active utilizando una aplicaci\u00f3n de billetera digital, Walletmor dice que podr\u00e1 realizar compras en la mayor\u00eda de las empresas de todo el mundo simplemente pasando la mano por un lector de tarjetas.<\/p>\n<p>Walletmor dice que casi 200 personas ya tienen los implantes.&nbsp;El procedimiento duele tanto como cuando alguien te pellizc\u00f3 la piel, seg\u00fan alguien a quien le inyectaron el implante debajo de la piel en 2019.<\/p>\n<p>Walletmor sugiere utilizar un cirujano o uno de sus especialistas de confianza para la operaci\u00f3n menor.<\/p>\n<p>Seg\u00fan los informes, funciona inmediatamente despu\u00e9s de ser implantado.\u00a0No se requiere bater\u00eda ni otra fuente de energ\u00eda, en caso de que se lo pregunte.\u00a0En su lugar, utiliza comunicaci\u00f3n de campo cercano.<\/p>\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/ismorbo.com\/wp-content\/uploads\/2022\/04\/laura-stevens-picture-press.jpg\" alt=\"As\u00ed son los microchips implantados bajo la piel que permiten pagar con  nuestra mano\" \/><\/figure>\n<p>Pero si tienes el remordimiento del comprador&#8230; l\u00e1stima.&nbsp;Una vez que se coloca el implante, no hay reembolsos.<\/p>\n<p>Actualmente, los chips solo se venden a ciudadanos del Reino Unido, Suiza y pa\u00edses de la Uni\u00f3n Europea.<\/p>\n<p>\u00bfOptar\u00edas por la opci\u00f3n de pago?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En lugar de llevar la billetera en el bolso o en el bolsillo trasero, una empresa de tecnolog\u00eda quiere que la lleve debajo de la piel. \u00a1C\u00f3mo es eso por conveniencia!\u00a0O es genial o dist\u00f3pico. La empresa brit\u00e1nico-polaca\u00a0Walletmor\u00a0vende microchips como opciones de pago alternativas que le permiten pagar con la mano. Este chip es del [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3102","post","type-post","status-publish","format-standard","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/posts\/3102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/comments?post=3102"}],"version-history":[{"count":0,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/posts\/3102\/revisions"}],"wp:attachment":[{"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/media?parent=3102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/categories?post=3102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/tags?post=3102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}