{"id":3110,"date":"2022-04-06T18:17:01","date_gmt":"2022-04-06T18:17:01","guid":{"rendered":"https:\/\/charangalatina.cl\/nuevaweb\/mcdonalds-vinculado-a-la-deforestacion-del-amazonas-en-un-nuevo-informe\/"},"modified":"2022-04-06T18:17:01","modified_gmt":"2022-04-06T18:17:01","slug":"mcdonalds-vinculado-a-la-deforestacion-del-amazonas-en-un-nuevo-informe","status":"publish","type":"post","link":"https:\/\/charangalatina.cl\/nuevaweb\/mcdonalds-vinculado-a-la-deforestacion-del-amazonas-en-un-nuevo-informe\/","title":{"rendered":"McDonald\u2019s vinculado a la deforestaci\u00f3n del Amazonas en un nuevo informe"},"content":{"rendered":"<p>Un grupo brasile\u00f1o alega que las empresas que suministran carne de res a la cadena de restaurantes han comprado ganado proveniente de ranchos desmontados ilegalmente.<\/p>\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/static.nationalgeographic.es\/files\/styles\/image_3200\/public\/1200px-operacao_hymenaea_julho-2016_29399454651.jpg?w=1600&amp;h=900\" alt=\"La deforestaci\u00f3n del Amazonas alcanza niveles hist\u00f3ricos debido al consumo  de carne | National Geographic\" \/><\/figure>\n<p>McDonald&#8217;s Corp.\u00a0\u00a0tiene v\u00ednculos con la deforestaci\u00f3n y los abusos laborales en los humedales del Pantanal de Brasil y en la selva amaz\u00f3nica, que desempe\u00f1a un papel crucial en la regulaci\u00f3n del clima mundial, seg\u00fan un informe publicado el mi\u00e9rcoles por\u00a0Reporter Brasil\u00a0, un grupo de investigaci\u00f3n independiente centrado en temas ambientales y laborales. cuestiones.\u00a0<\/p>\n<p>En su informe, Reporter Brasil revis\u00f3 varios casos en los que la carne de res de ranchos despejados ilegalmente se baraj\u00f3 entre granjas para ocultar su verdadero origen y luego se envi\u00f3 a mataderos propiedad de empresas que abastecen a McDonald&#8217;s.&nbsp;Los sindicatos en Europa se est\u00e1n apoyando en el informe para exigir que McDonald&#8217;s comience a divulgar anualmente los riesgos detallados de los derechos humanos y los abusos ambientales en su cadena de suministro, citando una&nbsp;<strong>&nbsp;<\/strong>ley de vigilancia francesa que los grupos ambientalistas esperan que sea un modelo para otros pa\u00edses.<\/p>\n<p>McDonald&#8217;s se neg\u00f3 a comentar antes de que se publicara el informe.\u00a0El\u00a0sitio web\u00a0de la compa\u00f1\u00eda dice que m\u00e1s del 99% de la carne de res que obtuvo a fines de 2020 \u00abapoy\u00f3 cadenas de suministro libres de deforestaci\u00f3n\u00bb.\u00a0El gigante de la comida r\u00e1pida ha\u00a0luchado para frenar\u00a0su enorme huella de carbono.<\/p>\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mongabay-images.s3.amazonaws.com\/15\/0421mcdonalds.jpg\" alt=\"McDonald's to address deforestation across all commodities it sources\" width=\"1023\" height=\"776\" \/><\/figure>\n<p>La cadena de suministro de carne de res de Brasil, una de las m\u00e1s complejas del mundo, es la principal culpable de la deforestaci\u00f3n de la Amazon\u00eda,\u00a0que alcanz\u00f3 un m\u00e1ximo de 15 a\u00f1os en 2021\u00a0.\u00a0En un extremo de la cadena hay 2,5 millones de ganaderos, muchos de ellos en rincones remotos de Brasil sin protecci\u00f3n, control o aplicaci\u00f3n del gobierno.\u00a0Por otro lado est\u00e1n los compradores corporativos en 80 pa\u00edses.\u00a0JBS SA\u00a0,\u00a0Marfrig Global Foods SA\u00a0y\u00a0Minerva SA\u00a0, los exportadores de carne de res m\u00e1s grandes de Brasil, dicen que establecen los est\u00e1ndares m\u00e1s altos para eliminar a los malos actores de su cadena de suministro, pero\u00a0una investigaci\u00f3n de Bloomberg Green en enero\u00a0mostr\u00f3 c\u00f3mo es el viaje de una vaca desde el nacimiento hasta la granja de engorde. dejado casi en su totalidad sin control.\u00a0<\/p>\n<p>La ley de vigilancia francesa de 2017 exige que las empresas con m\u00e1s de 10 000 empleados en todo el mundo supervisen sus cadenas de suministro completas y creen planes para evitar riesgos ambientales, de derechos humanos y de corrupci\u00f3n.\u00a0Si bien no existen sanciones duras y r\u00e1pidas por violar la ley, s\u00ed pone de relieve las malas pr\u00e1cticas corporativas en un momento en que los inversionistas est\u00e1n\u00a0descontando\u00a0cada vez m\u00e1s\u00a0acciones y bonos con modelos comerciales insostenibles.\u00a0Los grupos ambientalistas est\u00e1n presionando para expandir la ley, tanto en alcance como a otros pa\u00edses, y tambi\u00e9n han apuntado a la cadena de supermercados\u00a0Casino Guichard-Perrachon SA\u00a0y al productor de petr\u00f3leo\u00a0TotalEnergies SE\u00a0utilizando la legislaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un grupo brasile\u00f1o alega que las empresas que suministran carne de res a la cadena de restaurantes han comprado ganado proveniente de ranchos desmontados ilegalmente. McDonald&#8217;s Corp.\u00a0\u00a0tiene v\u00ednculos con la deforestaci\u00f3n y los abusos laborales en los humedales del Pantanal de Brasil y en la selva amaz\u00f3nica, que desempe\u00f1a un papel crucial en la regulaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3110","post","type-post","status-publish","format-standard","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/posts\/3110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/comments?post=3110"}],"version-history":[{"count":0,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/posts\/3110\/revisions"}],"wp:attachment":[{"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/media?parent=3110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/categories?post=3110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/tags?post=3110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}