{"id":3121,"date":"2022-04-01T08:02:00","date_gmt":"2022-04-01T08:02:00","guid":{"rendered":"https:\/\/charangalatina.cl\/nuevaweb\/el-heroe-de-accion-de-hollywood-bruce-willis-se-retirara-tras-un-diagnostico-medico\/"},"modified":"2022-04-01T08:02:00","modified_gmt":"2022-04-01T08:02:00","slug":"el-heroe-de-accion-de-hollywood-bruce-willis-se-retirara-tras-un-diagnostico-medico","status":"publish","type":"post","link":"https:\/\/charangalatina.cl\/nuevaweb\/el-heroe-de-accion-de-hollywood-bruce-willis-se-retirara-tras-un-diagnostico-medico\/","title":{"rendered":"El h\u00e9roe de acci\u00f3n de Hollywood Bruce Willis se retirar\u00e1 tras un diagn\u00f3stico m\u00e9dico"},"content":{"rendered":"<p>El actor ha sido diagnosticado con afasia, lo que est\u00e1 afectando sus capacidades cognitivas.<\/p>\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static1.elcomercio.es\/www\/multimedia\/202203\/30\/media\/cortadas\/bruce-willis-khyB-U1601502818469x5H-624x385@El%20Comercio.jpg\" alt=\"Qu\u00e9 es la afasia, la enfermedad que padece Bruce Willis | El Comercio\" width=\"1018\" height=\"630\" \/><\/figure>\n<p>Los \u00c1ngeles: La estrella de \u00abDie Hard\u00bb Bruce Willis se retirar\u00e1 de su carrera como actor luego de que le diagnosticaran afasia, una enfermedad que est\u00e1 \u00abafectando sus habilidades cognitivas\u00bb, dijo su familia en un comunicado el mi\u00e9rcoles.<\/p>\n<p>\u00abBruce ha estado experimentando algunos problemas de salud y recientemente le diagnosticaron afasia, lo que est\u00e1 afectando sus habilidades cognitivas\u00bb, dec\u00eda una publicaci\u00f3n en Instagram firmada por su familia.<\/p>\n<p>\u00abComo resultado de esto y con mucha consideraci\u00f3n, Bruce se est\u00e1 alejando de la carrera que ha significado tanto para \u00e9l\u00bb.<\/p>\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 es la afasia?<\/h2>\n<p>\u00abLa afasia simplemente significa que alguien tiene un problema con el lenguaje con el que no naci\u00f3\u00bb, explic\u00f3 Hugo Botha, neur\u00f3logo de la Cl\u00ednica Mayo en Minnesota.<\/p>\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.oroitu.com\/wp-content\/uploads\/2020\/10\/Afasia-Alzheimer.jpg\" alt=\"C\u00f3mo influye la afasia en las personas que sufren Alzheimer\" \/><\/figure>\n<p>La causa m\u00e1s com\u00fan es un derrame cerebral o una lesi\u00f3n en la cabeza, y los expertos enfatizan que, si bien puede afectar la producci\u00f3n y comprensi\u00f3n tanto del habla como de las palabras escritas, normalmente no afecta la inteligencia.<\/p>\n<p>Afecta a unos dos millones de estadounidenses, seg\u00fan la Asociaci\u00f3n Nacional de Afasia, por lo que es m\u00e1s com\u00fan que la enfermedad de Parkinson, la par\u00e1lisis cerebral o la distrofia muscular.&nbsp;Una encuesta de 2016 realizada por el mismo grupo encontr\u00f3 que menos del nueve por ciento de las personas sab\u00edan qu\u00e9 era.<\/p>\n<p>Si bien normalmente es causado por un evento \u00fanico espec\u00edfico, como un accidente cerebrovascular, \u00abexisten otras posibilidades, como una enfermedad neurodegenerativa\u00bb o un tumor en crecimiento, explic\u00f3 Brenda Rapp, cient\u00edfica cognitiva de la Universidad Johns Hopkins.<\/p>\n<p>En tales casos, el da\u00f1o es progresivo y la terapia se enfoca en prevenir una mayor p\u00e9rdida de funci\u00f3n.&nbsp;La familia de Willis no comparti\u00f3 la causa de su diagn\u00f3stico en su declaraci\u00f3n.<\/p>\n<h2 class=\"wp-block-heading\">\u00bfCu\u00e1les son las diferentes formas?<\/h2>\n<p>El sistema cerebral que gobierna el lenguaje es una \u00abm\u00e1quina muy compleja\u00bb que implica seleccionar las palabras correctas, mover la boca apropiadamente para vocalizarlas y, por otro lado, escuchar y decodificar su significado, dijo Rapp.<\/p>\n<p>De vez en cuando, a todo el mundo le cuesta encontrar la palabra correcta, \u00abpero se puede imaginar en la afasia, esto sucede mucho\u00bb, agreg\u00f3.&nbsp;Los m\u00e9dicos a veces dividen la afasia en categor\u00edas cl\u00ednicas amplias que se correlacionan con el lugar del cerebro donde ocurri\u00f3 la lesi\u00f3n.<\/p>\n<p>En la afasia expresiva, las personas \u00abgeneralmente entienden bastante bien pero tienen problemas para pronunciar las palabras\u00bb, dijo la pat\u00f3loga del habla Brooke Hatfield, de la Asociaci\u00f3n Estadounidense del Habla, Lenguaje y Audici\u00f3n (ASHA).<\/p>\n<p>Una persona con este tipo de afasia puede usar oraciones simples como \u00abquiero comida\u00bb para que se le entienda.&nbsp;En la afasia receptiva \u00ablas palabras salen con facilidad, pero es posible que no sean las correctas. Y es dif\u00edcil para esa persona entender lo que est\u00e1 escuchando\u00bb, agreg\u00f3 Hatfield.<\/p>\n<p>La afasia global tiene componentes expresivos y receptivos.<\/p>\n<h2 class=\"wp-block-heading\">Terapia del lenguaje<\/h2>\n<p>La buena noticia, dice Hatfield, es que las personas pueden mejorar a largo plazo.<\/p>\n<p>\u00abHay personas que sufrieron un derrame cerebral hace 30 a\u00f1os, que a\u00fan trabajan en su lenguaje y comunicaci\u00f3n y a\u00fan logran avances\u00bb.<\/p>\n<p>El cerebro es extremadamente pl\u00e1stico, y la terapia del habla puede involucrar otras partes del mismo para \u00abpasar por alto los obst\u00e1culos\u00bb de las \u00e1reas da\u00f1adas y forjar nuevas conexiones, dijo Rapp.&nbsp;Dicha terapia tambi\u00e9n ense\u00f1a a las personas a hablar sobre el tema si se atascan en una palabra espec\u00edfica.&nbsp;Los miembros de la familia tambi\u00e9n pueden desarrollar estrategias para hacerse entender mejor: \u00abCosas como oraciones m\u00e1s cortas y asegurarse de que est\u00e1 hablando con la persona a la vista en lugar de con la otra habitaci\u00f3n, y minimizar el ruido de fondo\u00bb, dijo Botha.<\/p>\n<p>A algunas personas les va bien con los dispositivos de asistencia porque su capacidad para escribir no se ve afectada de la misma manera.&nbsp;En el horizonte, hay tratamientos experimentales que combinan la estimulaci\u00f3n el\u00e9ctrica del cerebro con la terapia del habla que se han mostrado prometedores en la recuperaci\u00f3n de la funci\u00f3n, dijo Rapp.<\/p>\n<p>En el caso de la afasia progresiva, se cree que el camino a seguir es el desarrollo de medicamentos que apunten a la acumulaci\u00f3n de placas de prote\u00ednas y ovillos en el cerebro que causan enfermedades neurodegenerativas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El actor ha sido diagnosticado con afasia, lo que est\u00e1 afectando sus capacidades cognitivas. Los \u00c1ngeles: La estrella de \u00abDie Hard\u00bb Bruce Willis se retirar\u00e1 de su carrera como actor luego de que le diagnosticaran afasia, una enfermedad que est\u00e1 \u00abafectando sus habilidades cognitivas\u00bb, dijo su familia en un comunicado el mi\u00e9rcoles. \u00abBruce ha estado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3121","post","type-post","status-publish","format-standard","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/posts\/3121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/comments?post=3121"}],"version-history":[{"count":0,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/posts\/3121\/revisions"}],"wp:attachment":[{"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/media?parent=3121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/categories?post=3121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/tags?post=3121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}