{"id":3152,"date":"2022-03-17T17:55:38","date_gmt":"2022-03-17T17:55:38","guid":{"rendered":"https:\/\/charangalatina.cl\/nuevaweb\/netflix-esta-transmitiendo-la-serie-volodymyr-zelensky-que-presagio-su-presidencia\/"},"modified":"2022-03-17T17:55:38","modified_gmt":"2022-03-17T17:55:38","slug":"netflix-esta-transmitiendo-la-serie-volodymyr-zelensky-que-presagio-su-presidencia","status":"publish","type":"post","link":"https:\/\/charangalatina.cl\/nuevaweb\/netflix-esta-transmitiendo-la-serie-volodymyr-zelensky-que-presagio-su-presidencia\/","title":{"rendered":"Netflix est\u00e1 transmitiendo la serie Volodymyr Zelensky que presagi\u00f3 su presidencia"},"content":{"rendered":"<p>Antes de convertirse en presidente de Ucrania, Volodymyr Zelensky\u00a0era un exitoso actor y comediante.<\/p>\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.hola.com\/us\/images\/0273-14adf6d6796e-d40b2fcd7a03-1000\/horizontal-800\/ukrainian-president-volodymyr-zelensky-s-comedy-series-is-back-on-netflix.jpg\" alt=\"Ukrainian President Volodymyr Zelensky's satirical series returns to Netflix\" width=\"1020\" height=\"612\" \/><\/figure>\n<p>Ahora Netflix est\u00e1 transmitiendo nuevamente la serie de televisi\u00f3n que lo ayud\u00f3 a convertirse en una estrella y sirvi\u00f3 como trampol\u00edn para su campa\u00f1a presidencial.\u00bbServant of the People\u00bb\u00a0es una s\u00e1tira pol\u00edtica que presenta a Zelensky como un maestro de secundaria que se convierte en presidente de Ucrania despu\u00e9s de que un discurso que hace sobre la corrupci\u00f3n en el gobierno del pa\u00eds se vuelve viral.<\/p>\n<p>La serie se estren\u00f3 en 2015. Algunos han atribuido al papel ayudar a catapultar a Zelensky a la presidencia de la vida real de Ucrania en 2019.<\/p>\n<p>\u00ab\u00a1T\u00fa preguntaste y est\u00e1 de vuelta!\u00bb\u00a0Netflix\u00a0dijo en un tuit\u00a0el mi\u00e9rcoles, anunciando el regreso de la serie.Zelensky domina actualmente el escenario mundial con\u00a0sus apasionadas s\u00faplicas de ayuda\u00a0tras la invasi\u00f3n de Rusia a su pa\u00eds.<\/p>\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/phantom-marca.unidadeditorial.es\/9fb35ef311ab46dce5f7f0514b70a6f8\/resize\/1320\/f\/jpg\/assets\/multimedia\/imagenes\/2021\/06\/05\/16229091585309.jpg\" alt=\"Top 10 Netflix shows to watch this weekend | Marca\" \/><\/figure>\n<p>En \u00abServant of the People\u00bb, el profesor de secundaria Vasiliy Petrovich Goloborodko, interpretado por Zelenskyy, lanza una diatriba contra la corrupci\u00f3n del gobierno.\u00a0La diatriba se vuelve viral en las redes sociales y se convierte en el nuevo presidente del pa\u00eds.<\/p>\n<p>En la vida real, Zelenskyy\u00a0se present\u00f3 en una plataforma similar,\u00a0usando el nombre del programa como el nombre de su partido.\u00a0Termin\u00f3 derrotando al expresidente ucraniano Petro Poroshenko en una segunda vuelta en 2019, con m\u00e1s del 70% de los votos.\u00a0<\/p>\n<p>Antes de su presidencia, Zelenskyy tuvo una larga carrera como animador, e incluso gan\u00f3 la versi\u00f3n de su pa\u00eds de \u00abBailando con las estrellas\u00bb en 2006.<\/p>\n<p>Sin embargo, recibi\u00f3 su reconocimiento mundial como el feroz l\u00edder de su pa\u00eds durante\u00a0la invasi\u00f3n no provocada de Rusia\u00a0.\u00a0Incluso ha prometido permanecer en Ucrania, a pesar del peligro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Antes de convertirse en presidente de Ucrania, Volodymyr Zelensky\u00a0era un exitoso actor y comediante. Ahora Netflix est\u00e1 transmitiendo nuevamente la serie de televisi\u00f3n que lo ayud\u00f3 a convertirse en una estrella y sirvi\u00f3 como trampol\u00edn para su campa\u00f1a presidencial.\u00bbServant of the People\u00bb\u00a0es una s\u00e1tira pol\u00edtica que presenta a Zelensky como un maestro de secundaria que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3152","post","type-post","status-publish","format-standard","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/posts\/3152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/comments?post=3152"}],"version-history":[{"count":0,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/posts\/3152\/revisions"}],"wp:attachment":[{"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/media?parent=3152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/categories?post=3152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/tags?post=3152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}