{"id":3176,"date":"2022-03-07T15:34:28","date_gmt":"2022-03-07T15:34:28","guid":{"rendered":"https:\/\/charangalatina.cl\/nuevaweb\/violencia-extrema-en-el-futbol-mexicano-batalla-campal-entre-hinchas-de-queretaro-y-atlas\/"},"modified":"2022-03-07T15:34:28","modified_gmt":"2022-03-07T15:34:28","slug":"violencia-extrema-en-el-futbol-mexicano-batalla-campal-entre-hinchas-de-queretaro-y-atlas","status":"publish","type":"post","link":"https:\/\/charangalatina.cl\/nuevaweb\/violencia-extrema-en-el-futbol-mexicano-batalla-campal-entre-hinchas-de-queretaro-y-atlas\/","title":{"rendered":"\ufffcViolencia extrema en el f\u00fatbol mexicano, batalla campal entre hinchas de Quer\u00e9taro y Atlas."},"content":{"rendered":"<p>El horror de la violencia en M\u00e9xico tambi\u00e9n se ha trasladado al f\u00fatbol. En lo que parec\u00eda ser un juego rutinario del f\u00fatbol mexicano, se desat\u00f3 una pelea monumental en las gradas que ha dejado im\u00e1genes para el olvido.<\/p>\n<p>El partido entre Quer\u00e9taro y Atlas termin\u00f3 en una batalla campal en diferentes puntos del estadio Corregidora, a dos horas del centro de la Ciudad de M\u00e9xico. Aficionados que no ten\u00edan intenci\u00f3n de pelear bajaron desesperados al terreno de juego para protegerse en la peor agresi\u00f3n que se registra entre aficionados en M\u00e9xico.<\/p>\n<p>Los futbolistas de ambos clubes se lanzaron a la carrera directos al vestuario. Solo se hab\u00edan jugado 62 minutos. Pasadas las nueve de la noche, las autoridades a\u00fan no hab\u00edan informado el n\u00famero exacto de heridos, que se arroja por decenas, y no se ha confirmado ninguna muerte, pese a que diversas informaciones as\u00ed lo apuntaban.<\/p>\n<p>La televisi\u00f3n mostr\u00f3 c\u00f3mo una familia de padre, madre y dos ni\u00f1os corr\u00edan por el c\u00e9sped para intentar protegerse. La seguridad del estadio, deficiente y desbordada, no pudo evitar guiar a la afici\u00f3n hacia los t\u00faneles de salida. La polic\u00eda no se ve en las im\u00e1genes de televisi\u00f3n. El arquero del equipo local, Washington Aguerre, pidi\u00f3 calma a su afici\u00f3n, pero no obtuvo respuesta. Al otro lado de la cancha, un aficionado ensangrentado suplicaba que dejaran de golpearlo. En el centro del campo, un hincha del Atl\u00e9tico protegi\u00f3 a su compa\u00f1ero de las patadas de un grupo de hombres indignados. Afuera del estadio continuaron las golpizas, e incluso se puede ver en videos de hinchas en redes sociales, hubo hinchas que terminaron ensangrentados y desnudos quienes, a pesar de quedar noqueados en el piso, continuaron recibiendo golpes.<\/p>\n<p><strong><em>\u201cInadmisible y lamentable la violencia en el estadio La Corregidora. Los responsables de la falta de seguridad en el estadio ser\u00e1n sancionados de manera ejemplar\u201d<\/em><\/strong>, conden\u00f3 <strong>Mikel Arriola<\/strong>, presidente de la <strong>Liga MX. <\/strong>A pesar del mensaje que se llen\u00f3 de likes, la jornada del futbol mexicano sigui\u00f3 como si nada. El gobernador del estado, <strong>Mauricio Kuri<\/strong>, apunt\u00f3 directamente contra el club: <strong><em>\u201cLa empresa propietaria de Gallos y las instituciones deben responder por los hechos\u201d.<\/em><\/strong><\/p>\n<p>No existe rivalidad entre Quer\u00e9taro y Atlas, sin embargo, los Gallos ya hab\u00edan protagonizado un episodio de violencia en octubre de 2019 cuando su afici\u00f3n inici\u00f3 una batalla en las gradas contra la afici\u00f3n del Atl\u00e9tico de San Luis, la franquicia del Atl\u00e9tico de San Luis. Madrid en M\u00e9xico. Esa vez solo hubo una amenaza de veto a la cancha por parte del alto mando del futbol mexicano y volvieron a la normalidad.<\/p>\n<p>En 2015, los Radicales del Atlas invadieron la cancha en un partido ante Chivas, su m\u00e1s cercano rival, con apenas 54 minutos de juego. La barra del equipo rojinegro baj\u00f3 a la cancha para increpar a sus futbolistas que perd\u00edan 4-1, la polic\u00eda tambi\u00e9n perdi\u00f3 el control en los primeros minutos, pero lograron proteger a los futbolistas y cerrar las entradas al campo.<\/p>\n<p>Esa vez s\u00f3lo se contabilizaron una docena de heridos y ning\u00fan muerto. La Federaci\u00f3n Mexicana de F\u00fatbol sancion\u00f3 al club con dos partidos sin aficionados en sus gradas.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El horror de la violencia en M\u00e9xico tambi\u00e9n se ha trasladado al f\u00fatbol. En lo que parec\u00eda ser un juego rutinario del f\u00fatbol mexicano, se desat\u00f3 una pelea monumental en las gradas que ha dejado im\u00e1genes para el olvido. El partido entre Quer\u00e9taro y Atlas termin\u00f3 en una batalla campal en diferentes puntos del estadio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3176","post","type-post","status-publish","format-standard","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/posts\/3176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/comments?post=3176"}],"version-history":[{"count":0,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/posts\/3176\/revisions"}],"wp:attachment":[{"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/media?parent=3176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/categories?post=3176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/tags?post=3176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}