{"id":3191,"date":"2022-02-28T16:11:51","date_gmt":"2022-02-28T16:11:51","guid":{"rendered":"https:\/\/charangalatina.cl\/nuevaweb\/la-escritora-ucraniana-iryna-tsvila-y-su-esposo-mueren-defendiendo-a-su-pais\/"},"modified":"2022-02-28T16:11:51","modified_gmt":"2022-02-28T16:11:51","slug":"la-escritora-ucraniana-iryna-tsvila-y-su-esposo-mueren-defendiendo-a-su-pais","status":"publish","type":"post","link":"https:\/\/charangalatina.cl\/nuevaweb\/la-escritora-ucraniana-iryna-tsvila-y-su-esposo-mueren-defendiendo-a-su-pais\/","title":{"rendered":"La escritora ucraniana Iryna Tsvila y su esposo mueren defendiendo a su pa\u00eds."},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/peru21.pe\/resizer\/BXns27d-AcsDKE5V110CyTxDmmo=\/580x330\/smart\/filters:format(jpeg):quality(75)\/cloudfront-us-east-1.images.arcpublishing.com\/elcomercio\/RTRF4ZARPBGN5EMB6GU6KDYDUM.jpg\" alt=\"Guerra Rusia Ucrania | Iryna Tsvila | Escritora ucraniana y mujer soldado Iryna  Tsvila muere en enfrentamiento con las fuerzas rusas | RMMN | MUNDO | PERU21\" width=\"832\" height=\"474\" \/><\/figure>\n<\/div>\n<p>La escritora ucraniana <strong>Iryna Tsvila<\/strong> muri\u00f3 junto a su compa\u00f1ero luchando contra las fuerzas invasoras rusas durante la defensa de Kiev, informaron diversos medios internacionales mientras Rusia contin\u00faa su embestida contra Ucrania.<\/p>\n<p>Madre de cinco hijos, <strong>Tsvila<\/strong> formaba parte de la Brigada de Respuesta de la Guardia Nacional del Ej\u00e9rcito de Ucrania y falleci\u00f3 con su esposo <strong>Dmytro<\/strong> el 26 de febrero, inform\u00f3 el medio De Limburger.<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"http:\/\/hsbnoticias.com\/sites\/default\/files\/2022-02\/ESCRITORA%20DE%20uCRANIA%201.JPG\" alt=\"No es ficci\u00f3n: Iryna Tsvila, escritora ucraniana, muri\u00f3 por defender Kiev  de los rusa [VIDEO] | HSB\" \/><\/figure>\n<\/div>\n<p><strong><em>\u201cLa escritora ucraniana Iryna Tsvila, autora de Voices of War. Historias de veteranos, ha muerto junto a su compa\u00f1ero Dmytro defendiendo Kiev de la invasi\u00f3n rusa\u201d,<\/em><\/strong> escribi\u00f3 en Twitter este domingo 27 de <strong>febrero Beatriz Becerra<\/strong>, tambi\u00e9n escritora y exdiputada del Parlamento Europeo.<\/p>\n<p><strong>Volodymyr Yermolenko<\/strong>, fil\u00f3sofo, analista y periodista ucraniano, lament\u00f3 la noticia en su cuenta oficial de Twitter. <strong><em>\u201cMi amiga fue asesinada hoy, Iryna Tsvila . Una persona incre\u00edblemente valiente y amable\u201d<\/em><\/strong>, dijo el 26 de febrero.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p lang=\"en\" dir=\"ltr\">my friend was killed today, Iryna Tsvila. Incredibly brave and kind person. Went through Donbas war as volunteer. Joined territorial defence now. We&#039;ve made a book recently, &quot;Voices of War. Stories of Veterans&quot;, she among authors. Wrote about her rose garden. Look at this smile <a href=\"https:\/\/t.co\/bSSwCLdL5t\">pic.twitter.com\/bSSwCLdL5t<\/a><\/p>\n<p>&mdash; Volodymyr Yermolenko (@yermolenko_v) <a href=\"https:\/\/twitter.com\/yermolenko_v\/status\/1497544639246704641?ref_src=twsrc%5Etfw\">February 26, 2022<\/a><\/p><\/blockquote>\n<p>As\u00ed hubo m\u00faltiples mensajes en las redes sociales en las \u00faltimas horas; mientras que en Kiev contin\u00faa la resistencia y de <strong><em>momento \u201cno hay tropas rusas\u201d,<\/em><\/strong> seg\u00fan el alcalde de la capital ucraniana, <strong>Vitaly Klitschko<\/strong>.<\/p>\n<p><strong><em>\u201cKiev contin\u00faa defendi\u00e9ndose.No hay tropas rusas en la ciudad, pero hay muchos grupos de saboteadores\u201d<\/em><\/strong>, dijo el concejal de Kiev en un mensaje difundido por su servicio de prensa.<\/p>\n<p>Agreg\u00f3 que el Ej\u00e9rcito y las fuerzas del orden han <strong><em>\u201cneutralizado con \u00e9xito algunos grandes grupos de saboteadores\u201d.<\/em><\/strong><\/p>\n<p><strong>Klitschko<\/strong> record\u00f3 que sigue vigente un toque de queda en la capital ucraniana y pidi\u00f3 a la gente que no salga de casa a menos que suene una sirena antia\u00e9rea.<\/p>\n<p>Seg\u00fan el alcalde de Kiev, nueve civiles, cuatro personas no identificadas y 18 combatientes han muerto en la ciudad desde el comienzo del ataque ruso.<\/p>\n<p>Agreg\u00f3 que la infraestructura clave de la ciudad funciona normalmente, pero el transporte p\u00fablico, incluido el metro, ha sido suspendido.<\/p>\n<p><strong><em>\u201cPido a todos que mantengan la calma y se queden en casa o en refugios\u201d,<\/em><\/strong> dijo <strong>Klitschko<\/strong>, quien asegur\u00f3 que los militares y las defensas territoriales defienden la ciudad.<\/p>\n<p><strong><em>\u201cLucharemos y venceremos\u201d,<\/em><\/strong> asegur\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La escritora ucraniana Iryna Tsvila muri\u00f3 junto a su compa\u00f1ero luchando contra las fuerzas invasoras rusas durante la defensa de Kiev, informaron diversos medios internacionales mientras Rusia contin\u00faa su embestida contra Ucrania. Madre de cinco hijos, Tsvila formaba parte de la Brigada de Respuesta de la Guardia Nacional del Ej\u00e9rcito de Ucrania y falleci\u00f3 con [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3191","post","type-post","status-publish","format-standard","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/posts\/3191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/comments?post=3191"}],"version-history":[{"count":0,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/posts\/3191\/revisions"}],"wp:attachment":[{"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/media?parent=3191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/categories?post=3191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/charangalatina.cl\/nuevaweb\/wp-json\/wp\/v2\/tags?post=3191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}